{"id":22154,"date":"2022-07-15T14:23:11","date_gmt":"2022-07-15T14:23:11","guid":{"rendered":"https:\/\/wholewordinstitute.com\/?p=22154"},"modified":"2022-07-15T14:24:55","modified_gmt":"2022-07-15T14:24:55","slug":"shavuot-and-pentecost-celebration-in-jerusalem","status":"publish","type":"post","link":"https:\/\/wholewordinstitute.com\/fr\/press-releases\/latest-news\/shavuot-and-pentecost-celebration-in-jerusalem\/","title":{"rendered":"C\u00e9l\u00e9bration de Shavuot et de la Pentec\u00f4te \u00e0 J\u00e9rusalem"},"content":{"rendered":"<p style=\"text-align: center\"><span style=\"color: #3a737f\"><em>Les premiers fruits de la Parole<\/em><\/span><\/p>\n<p>Le personnel et les \u00e9tudiants du Whole Word Institute se sont joints aux dirigeants venus du monde entier \u00e0 J\u00e9rusalem le jour de la Pentec\u00f4te pour une consultation sp\u00e9ciale. Ici, au Garden Tomb, ils ont partag\u00e9 un temps d'adoration, c\u00e9l\u00e9brant le don de la Parole et de l'Esprit. De nombreuses nations, y compris tous les continents, \u00e9taient repr\u00e9sent\u00e9es. Par cette consultation, le Whole Word Institute et ses partenaires cherchent \u00e0 jeter les bases initiales d'un mouvement qui, par la pri\u00e8re et la planification guid\u00e9e par l'Esprit, vise \u00e0 \u00e9liminer la lacune de l'Original (Ancien) Testament.<\/p>\n<p>En c\u00e9l\u00e9brant la Pentec\u00f4te, nous nous sommes particuli\u00e8rement rappel\u00e9s du r\u00f4le pr\u00e9pond\u00e9rant de l'Esprit de Dieu dans le don de Sa Parole \u00e0 toutes les nations. Lorsque Dieu a d\u00e9vers\u00e9 son Esprit sur ses disciples \u00e0 la Pentec\u00f4te, ceux-ci ont commenc\u00e9 \u00e0 d\u00e9clarer miraculeusement \"les merveilles de Dieu\" dans les langues maternelles des nombreuses nationalit\u00e9s qui s'\u00e9taient rendues \u00e0 J\u00e9rusalem pour Shavuot.<\/p>\n<p>Sans l'Ancien Testament, nous ne pouvons pas saisir toute la signification de ce moment de l'histoire de la r\u00e9demption. La Pentec\u00f4te trouve ses racines dans la f\u00eate de Shavuot, \u00e9galement connue sous le nom de \"f\u00eate des semaines\" ou de \"f\u00eate des premiers fruits\". Au cours de cette f\u00eate, le peuple de Dieu devait lui offrir ce qu'il avait de meilleur. Comme l'indiquent les Deut\u00e9ronomes 26 et 31, ces pr\u00e9mices devaient \u00eatre partag\u00e9es avec les l\u00e9vites, les enfants, les orphelins, les serviteurs, les \u00e9trangers, les veuves et les \u00e9trangers. Traditionnellement, Shavuot co\u00efncide avec la r\u00e9ception de la Torah, lorsque la gloire de Dieu est apparue dans un feu ardent sur le mont Sina\u00ef et que Mo\u00efse a transmis Sa Parole \u00e0 Isra\u00ebl.<\/p>\n<p>Lorsque l'Esprit de Dieu a souffl\u00e9 dans la maison \u00e0 la Pentec\u00f4te, et que les langues de flammes se sont pos\u00e9es sur chaque disciple, Dieu, de mani\u00e8re spectaculaire, a rappel\u00e9 le mont Sina\u00ef lorsqu'il a manifest\u00e9 sa pr\u00e9sence \u00e0 son peuple, et qu'Isra\u00ebl a re\u00e7u sa Parole. Mais ici, dans Actes 2, au lieu d'un sommet de montagne, Sa pr\u00e9sence reposait sur les disciples de J\u00e9sus, les impr\u00e9gnant de Sa Parole, qu'ils partageaient \u00e0 leur tour avec toute nation, tribu et langue. Pierre a \u00e9tabli ce lien profond lorsqu'il s'est lev\u00e9 pour s'adresser \u00e0 la foule \u00e0 la Pentec\u00f4te :<\/p>\n<p style=\"text-align: center\"><span style=\"color: #3a737f\"><em>\"Et dans les derniers jours, il en sera ainsi, Dieu le d\u00e9clare,\u00a0\u00a0<\/em><\/span><br \/>\n<span style=\"color: #3a737f\"><em>que je r\u00e9pandrai mon Esprit sur toute chair...\u00a0<\/em><\/span><br \/>\n<span style=\"color: #3a737f\"><em>Et il arrivera que toute personne qui appelle\u00a0<\/em><\/span><br \/>\n<span style=\"color: #3a737f\"><em>sur le nom du Seigneur sera sauv\u00e9.\"<br \/>\n-Actes 2:17, 21<\/em><\/span><\/p>\n<p>Comme le r\u00e9v\u00e8le toute l'histoire, le projet de Dieu d'habiter parmi son peuple se r\u00e9alisait, ouvrant grand les portes \u00e0 tous ceux qui invoquent le nom de J\u00e9sus.<\/p>\n<p>L'une des classes en ligne du Whole Word Institute, dans le cadre du Hebrew Extension Learning Program, \u00e9tudie actuellement le livre de Ruth, un livre traditionnel \u00e0 lire pendant Shavuot. Pendant la p\u00e9riode des r\u00e9coltes de Shavuot, Ruth, une \u00e9trang\u00e8re, a \u00e9t\u00e9 accueillie dans la maison d'Isra\u00ebl et est devenue membre de la lign\u00e9e royale de David.<\/p>\n<p>Ruth elle-m\u00eame pr\u00e9figurait les \u00e9trangers qui se rassembleraient \u00e0 J\u00e9rusalem \u00e0 Shavuot, peu apr\u00e8s que J\u00e9sus eut charg\u00e9 ses disciples de faire des disciples de toutes les nations.<\/p>\n<p xml:lang=\"EN-US\">Merci de partager la Parole,<\/p>\n<p xml:lang=\"EN-US\"><span style=\"color: #3a737f\"><strong>L'\u00e9quipe du Whole Word Institute\u00a0<\/strong><\/span><br \/>\n<span style=\"color: #e0ba64\"><strong><em>Le mot entier pour le monde entier<\/em><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Shalom ! Nous sommes ravis de partager avec vous notre rapport annuel 2021 - Demandez-moi : l'effet d'entra\u00eenement de la parole...<\/p>","protected":false},"author":16,"featured_media":22157,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[15],"tags":[],"class_list":["post-22154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-latest-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Shavuot and Pentecost Celebration in Jerusalem - Whole Word Institute<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wholewordinstitute.com\/fr\/press-releases\/latest-news\/shavuot-and-pentecost-celebration-in-jerusalem\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Shavuot and Pentecost Celebration in Jerusalem - Whole Word Institute\" \/>\n<meta property=\"og:description\" content=\"Shalom! We are excited to share with you our Annual Report 2021\u2014Ask of Me: The Ripple Effect of the Word...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wholewordinstitute.com\/fr\/press-releases\/latest-news\/shavuot-and-pentecost-celebration-in-jerusalem\/\" \/>\n<meta property=\"og:site_name\" content=\"Whole Word Institute\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-15T14:23:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-15T14:24:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wholewordinstitute.com\/wp-content\/uploads\/2022\/07\/Garden-Tomb-Group-Web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Paul Rob Helpname\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paul Rob Helpname\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wholewordinstitute.com\\\/press-releases\\\/latest-news\\\/shavuot-and-pentecost-celebration-in-jerusalem\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wholewordinstitute.com\\\/press-releases\\\/latest-news\\\/shavuot-and-pentecost-celebration-in-jerusalem\\\/\"},\"author\":{\"name\":\"Paul Rob Helpname\",\"@id\":\"https:\\\/\\\/wholewordinstitute.com\\\/#\\\/schema\\\/person\\\/9e04cd36f7bd1b4571e80a0348c1de28\"},\"headline\":\"Shavuot and Pentecost Celebration in Jerusalem\",\"datePublished\":\"2022-07-15T14:23:11+00:00\",\"dateModified\":\"2022-07-15T14:24:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wholewordinstitute.com\\\/press-releases\\\/latest-news\\\/shavuot-and-pentecost-celebration-in-jerusalem\\\/\"},\"wordCount\":511,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/wholewordinstitute.com\\\/press-releases\\\/latest-news\\\/shavuot-and-pentecost-celebration-in-jerusalem\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wholewordinstitute.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Garden-Tomb-Group-Web.jpg\",\"articleSection\":[\"Latest News\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wholewordinstitute.com\\\/press-releases\\\/latest-news\\\/shavuot-and-pentecost-celebration-in-jerusalem\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wholewordinstitute.com\\\/press-releases\\\/latest-news\\\/shavuot-and-pentecost-celebration-in-jerusalem\\\/\",\"url\":\"https:\\\/\\\/wholewordinstitute.com\\\/press-releases\\\/latest-news\\\/shavuot-and-pentecost-celebration-in-jerusalem\\\/\",\"name\":\"Shavuot and Pentecost Celebration in Jerusalem - Whole Word Institute\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wholewordinstitute.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wholewordinstitute.com\\\/press-releases\\\/latest-news\\\/shavuot-and-pentecost-celebration-in-jerusalem\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wholewordinstitute.com\\\/press-releases\\\/latest-news\\\/shavuot-and-pentecost-celebration-in-jerusalem\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wholewordinstitute.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Garden-Tomb-Group-Web.jpg\",\"datePublished\":\"2022-07-15T14:23:11+00:00\",\"dateModified\":\"2022-07-15T14:24:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/wholewordinstitute.com\\\/#\\\/schema\\\/person\\\/9e04cd36f7bd1b4571e80a0348c1de28\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wholewordinstitute.com\\\/press-releases\\\/latest-news\\\/shavuot-and-pentecost-celebration-in-jerusalem\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wholewordinstitute.com\\\/press-releases\\\/latest-news\\\/shavuot-and-pentecost-celebration-in-jerusalem\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wholewordinstitute.com\\\/press-releases\\\/latest-news\\\/shavuot-and-pentecost-celebration-in-jerusalem\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wholewordinstitute.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Garden-Tomb-Group-Web.jpg\",\"contentUrl\":\"https:\\\/\\\/wholewordinstitute.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Garden-Tomb-Group-Web.jpg\",\"width\":1600,\"height\":1067},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wholewordinstitute.com\\\/press-releases\\\/latest-news\\\/shavuot-and-pentecost-celebration-in-jerusalem\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wholewordinstitute.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shavuot and Pentecost Celebration in Jerusalem\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wholewordinstitute.com\\\/#website\",\"url\":\"https:\\\/\\\/wholewordinstitute.com\\\/\",\"name\":\"Whole Word Institute\",\"description\":\"The whole word for the whole world\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wholewordinstitute.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wholewordinstitute.com\\\/#\\\/schema\\\/person\\\/9e04cd36f7bd1b4571e80a0348c1de28\",\"name\":\"Paul Rob Helpname\",\"url\":\"https:\\\/\\\/wholewordinstitute.com\\\/fr\\\/author\\\/phelpname\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Shavuot and Pentecost Celebration in Jerusalem - Whole Word Institute","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wholewordinstitute.com\/fr\/press-releases\/latest-news\/shavuot-and-pentecost-celebration-in-jerusalem\/","og_locale":"fr_FR","og_type":"article","og_title":"Shavuot and Pentecost Celebration in Jerusalem - Whole Word Institute","og_description":"Shalom! We are excited to share with you our Annual Report 2021\u2014Ask of Me: The Ripple Effect of the Word...","og_url":"https:\/\/wholewordinstitute.com\/fr\/press-releases\/latest-news\/shavuot-and-pentecost-celebration-in-jerusalem\/","og_site_name":"Whole Word Institute","article_published_time":"2022-07-15T14:23:11+00:00","article_modified_time":"2022-07-15T14:24:55+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/wholewordinstitute.com\/wp-content\/uploads\/2022\/07\/Garden-Tomb-Group-Web.jpg","type":"image\/jpeg"}],"author":"Paul Rob Helpname","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Paul Rob Helpname","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wholewordinstitute.com\/press-releases\/latest-news\/shavuot-and-pentecost-celebration-in-jerusalem\/#article","isPartOf":{"@id":"https:\/\/wholewordinstitute.com\/press-releases\/latest-news\/shavuot-and-pentecost-celebration-in-jerusalem\/"},"author":{"name":"Paul Rob Helpname","@id":"https:\/\/wholewordinstitute.com\/#\/schema\/person\/9e04cd36f7bd1b4571e80a0348c1de28"},"headline":"Shavuot and Pentecost Celebration in Jerusalem","datePublished":"2022-07-15T14:23:11+00:00","dateModified":"2022-07-15T14:24:55+00:00","mainEntityOfPage":{"@id":"https:\/\/wholewordinstitute.com\/press-releases\/latest-news\/shavuot-and-pentecost-celebration-in-jerusalem\/"},"wordCount":511,"commentCount":0,"image":{"@id":"https:\/\/wholewordinstitute.com\/press-releases\/latest-news\/shavuot-and-pentecost-celebration-in-jerusalem\/#primaryimage"},"thumbnailUrl":"https:\/\/wholewordinstitute.com\/wp-content\/uploads\/2022\/07\/Garden-Tomb-Group-Web.jpg","articleSection":["Latest News"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wholewordinstitute.com\/press-releases\/latest-news\/shavuot-and-pentecost-celebration-in-jerusalem\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wholewordinstitute.com\/press-releases\/latest-news\/shavuot-and-pentecost-celebration-in-jerusalem\/","url":"https:\/\/wholewordinstitute.com\/press-releases\/latest-news\/shavuot-and-pentecost-celebration-in-jerusalem\/","name":"Shavuot and Pentecost Celebration in Jerusalem - Whole Word Institute","isPartOf":{"@id":"https:\/\/wholewordinstitute.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wholewordinstitute.com\/press-releases\/latest-news\/shavuot-and-pentecost-celebration-in-jerusalem\/#primaryimage"},"image":{"@id":"https:\/\/wholewordinstitute.com\/press-releases\/latest-news\/shavuot-and-pentecost-celebration-in-jerusalem\/#primaryimage"},"thumbnailUrl":"https:\/\/wholewordinstitute.com\/wp-content\/uploads\/2022\/07\/Garden-Tomb-Group-Web.jpg","datePublished":"2022-07-15T14:23:11+00:00","dateModified":"2022-07-15T14:24:55+00:00","author":{"@id":"https:\/\/wholewordinstitute.com\/#\/schema\/person\/9e04cd36f7bd1b4571e80a0348c1de28"},"breadcrumb":{"@id":"https:\/\/wholewordinstitute.com\/press-releases\/latest-news\/shavuot-and-pentecost-celebration-in-jerusalem\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wholewordinstitute.com\/press-releases\/latest-news\/shavuot-and-pentecost-celebration-in-jerusalem\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wholewordinstitute.com\/press-releases\/latest-news\/shavuot-and-pentecost-celebration-in-jerusalem\/#primaryimage","url":"https:\/\/wholewordinstitute.com\/wp-content\/uploads\/2022\/07\/Garden-Tomb-Group-Web.jpg","contentUrl":"https:\/\/wholewordinstitute.com\/wp-content\/uploads\/2022\/07\/Garden-Tomb-Group-Web.jpg","width":1600,"height":1067},{"@type":"BreadcrumbList","@id":"https:\/\/wholewordinstitute.com\/press-releases\/latest-news\/shavuot-and-pentecost-celebration-in-jerusalem\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wholewordinstitute.com\/"},{"@type":"ListItem","position":2,"name":"Shavuot and Pentecost Celebration in Jerusalem"}]},{"@type":"WebSite","@id":"https:\/\/wholewordinstitute.com\/#website","url":"https:\/\/wholewordinstitute.com\/","name":"Institut du mot entier","description":"Le mot entier pour le monde entier","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wholewordinstitute.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/wholewordinstitute.com\/#\/schema\/person\/9e04cd36f7bd1b4571e80a0348c1de28","name":"Paul Rob Helpname","url":"https:\/\/wholewordinstitute.com\/fr\/author\/phelpname\/"}]}},"_links":{"self":[{"href":"https:\/\/wholewordinstitute.com\/fr\/wp-json\/wp\/v2\/posts\/22154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wholewordinstitute.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wholewordinstitute.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wholewordinstitute.com\/fr\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/wholewordinstitute.com\/fr\/wp-json\/wp\/v2\/comments?post=22154"}],"version-history":[{"count":2,"href":"https:\/\/wholewordinstitute.com\/fr\/wp-json\/wp\/v2\/posts\/22154\/revisions"}],"predecessor-version":[{"id":22156,"href":"https:\/\/wholewordinstitute.com\/fr\/wp-json\/wp\/v2\/posts\/22154\/revisions\/22156"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wholewordinstitute.com\/fr\/wp-json\/wp\/v2\/media\/22157"}],"wp:attachment":[{"href":"https:\/\/wholewordinstitute.com\/fr\/wp-json\/wp\/v2\/media?parent=22154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wholewordinstitute.com\/fr\/wp-json\/wp\/v2\/categories?post=22154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wholewordinstitute.com\/fr\/wp-json\/wp\/v2\/tags?post=22154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}